{"id":626362,"date":"2014-04-16T20:30:44","date_gmt":"2014-04-16T18:30:44","guid":{"rendered":"https:\/\/2014.hamburg.wordcamp.org\/?post_type=wcb_sponsor&#038;p=626362"},"modified":"2014-05-30T11:48:08","modified_gmt":"2014-05-30T09:48:08","slug":"wir-lieben-wp","status":"publish","type":"wcb_sponsor","link":"https:\/\/hamburg.wordcamp.org\/2014\/sponsor\/wir-lieben-wp\/","title":{"rendered":"Wir lieben WP"},"content":{"rendered":"<p><a href=\"https:\/\/wirliebenwp.de\/\" rel=\"nofollow\">Wir lieben WordPress<\/a> bietet einfach faires <a href=\"https:\/\/wirliebenwp.de\/wordpress-hosting\/leistung\/\" rel=\"nofollow\">WordPress Hosting<\/a> <a href=\"https:\/\/wirliebenwp.de\/wordpress-hosting\/server-in-deutschland\/\" rel=\"nofollow\">in und aus Deutschland<\/a>. Unsere Kunden bekommen einen fertig eingerichteten und SEO optimierten WordPress Blog, mit dem sie sofort loslegen k\u00f6nnen. Wir k\u00fcmmern uns um die Technik, unsere Kunden um ihre Inhalte. Warum? Weil wir wollen, dass auch kleine Unternehmen und Privatpersonen in der Liga der gro\u00dfen mitspielen k\u00f6nnen.<br \/>\n<a href=\"https:\/\/wirliebenwp.de\/wordpress-hosting\/einfach\/\" rel=\"nofollow\">Einfache Bedienung<\/a> des WordPress-Blogs ist unser oberstes Ziel. Wir wollen, dass Bloggen so einfach ist, wie einen Text in Word zu schreiben, oder eine E-Mail zu senden. Daher haben wir alle m\u00f6glichen Optionen bereits vorkonfiguriert.<\/p>\n<p><a href=\"https:\/\/wirliebenwp.de\/wordpress-hosting\/sicherheit\/\" rel=\"nofollow\">Sicherheit<\/a> ist elementarer Bestandteil all unserer Pakete. Spezialisiertes Wissen ist teuer und die Angriffe auf Content Management Systeme sind zahlreich. Ist es da nicht viel bequemer, sich auf die Erfahrung und das Wissen von Profis verlassen zu k\u00f6nnen?<\/p>\n<p><a href=\"https:\/\/wirliebenwp.de\/wordpress-hosting\/leistung\/\" rel=\"nofollow\">Qualit\u00e4t<\/a> ist unser Ma\u00dfstab. Plugins und Themes werden erst zur Verf\u00fcgung gestellt, wenn sie unsere Anforderungen erf\u00fcllen und einen Mehrwert bieten. Bei uns z\u00e4hlt Qualit\u00e4t statt Quantit\u00e4t.<\/p>\n<p><a href=\"https:\/\/wirliebenwp.de\/preise\/\" rel=\"nofollow\">Fairness und Transparenz<\/a> stehen ganz weit oben bei den Anforderungen an ein WLWP Paket. Wir verstecken keine unfairen Klauseln im Kleingedruckten. Wir bieten <a href=\"https:\/\/wirliebenwp.de\/wordpress-hosting\/deutscher-support\/\" rel=\"nofollow\">deutschen Support<\/a> f\u00fcr WordPress Liebhaber von WordPress Liebhabern. Unsere <a href=\"https:\/\/wirliebenwp.de\/wordpress-hosting\/vision\/\" rel=\"nofollow\">Vision<\/a> ist es, jedem das Bloggen zu erm\u00f6glichen!<\/p>\n<p>Einfach, sicher, professionell und fair &#8211; Was wir anbieten, w\u00fcrden wir auch selbst abschlie\u00dfen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir lieben WordPress bietet einfach faires WordPress Hosting in und aus Deutschland. Unsere Kunden bekommen einen fertig eingerichteten und SEO optimierten WordPress Blog, mit dem sie sofort loslegen k\u00f6nnen. Wir k\u00fcmmern uns um die Technik, unsere Kunden um ihre Inhalte. Warum? Weil wir wollen, dass auch kleine Unternehmen und Privatpersonen in der Liga der gro\u00dfen [&hellip;]<\/p>\n","protected":false},"featured_media":627360,"template":"","meta":{"_wcpt_sponsor_website":"https:\/\/wirliebenwp.de\/","footnotes":""},"sponsor_level":[267050],"class_list":["post-626362","wcb_sponsor","type-wcb_sponsor","status-publish","has-post-thumbnail","hentry","wcb_sponsor_level-silber"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheVcj-2CWC","_links":{"self":[{"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/sponsors\/626362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/sponsors"}],"about":[{"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/types\/wcb_sponsor"}],"version-history":[{"count":3,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/sponsors\/626362\/revisions"}],"predecessor-version":[{"id":626409,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/sponsors\/626362\/revisions\/626409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/media\/627360"}],"wp:attachment":[{"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/media?parent=626362"}],"wp:term":[{"taxonomy":"wcb_sponsor_level","embeddable":true,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/sponsor_level?post=626362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}