{"id":626787,"date":"2014-05-15T19:07:36","date_gmt":"2014-05-15T17:07:36","guid":{"rendered":"https:\/\/2014.hamburg.wordcamp.org\/?post_type=wcb_session&#038;p=626787"},"modified":"2014-05-15T23:09:32","modified_gmt":"2014-05-15T21:09:32","slug":"hooks-filter-actions-was-zum-geier-ist-das","status":"publish","type":"wcb_session","link":"https:\/\/hamburg.wordcamp.org\/2014\/session\/hooks-filter-actions-was-zum-geier-ist-das\/","title":{"rendered":"Hooks, Filter, Actions &#8211; Was zum Geier ist das?"},"content":{"rendered":"<p>Speaker:\u00a0Frank Staude<\/p>\n<p>Nicht \u201eWas die Welt im Innersten zusammenh\u00e4lt\u201c sondern was uns WordPress m\u00f6glichst weit \u00f6ffnet, das sind die Hooks. Egal ob Theme oder Plugin, um etwas in WordPress zu \u00e4ndern, zu erweitern, umzubauen und das ohne das man direkt im WordPress Code \u00e4ndert, dazu muss man verstehen was Hooks sind und wie diese Funktionieren. Egal ob man ein Komplexes Plugin bauen m\u00f6chte oder nur in seinem verwendeten Theme z.B. den Titel der Beitr\u00e4ge manipulieren m\u00f6chte. In dieser Session erkl\u00e4re ich wie das mit den Hooks, Filter und Actions funktioniert und zeige an konkreten Beispielen wie man sich da einklingt.<\/p>\n<p>Themenbereich: Anwendung<br \/>\nZielgruppe: Fortgeschritten<br \/>\nFormat: Session<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Speaker:\u00a0Frank Staude Nicht \u201eWas die Welt im Innersten zusammenh\u00e4lt\u201c sondern was uns WordPress m\u00f6glichst weit \u00f6ffnet, das sind die Hooks. Egal ob Theme oder Plugin, um etwas in WordPress zu \u00e4ndern, zu erweitern, umzubauen und das ohne das man direkt im WordPress Code \u00e4ndert, dazu muss man verstehen was Hooks sind und wie diese Funktionieren. [&hellip;]<\/p>\n","protected":false},"author":7406396,"featured_media":0,"template":"","meta":{"_wcpt_session_time":1402828200,"_wcpt_session_duration":3000,"_wcpt_session_type":"session","_wcpt_session_slides":"","_wcpt_session_video":"","_wcpt_speaker_id":[626638],"footnotes":""},"session_track":[277775],"session_category":[],"class_list":["post-626787","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-marketpress-saal"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheVcj-2D3t","session_date_time":{"date":"15. Juni 2014","time":"12:30"},"session_speakers":[{"id":"626638","slug":"frank-staude","name":"Frank Staude","link":"https:\/\/hamburg.wordcamp.org\/2014\/speaker\/frank-staude\/"}],"session_cats_rendered":null,"_links":{"self":[{"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/sessions\/626787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/types\/wcb_session"}],"version-history":[{"count":3,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/sessions\/626787\/revisions"}],"predecessor-version":[{"id":626977,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/sessions\/626787\/revisions\/626977"}],"speakers":[{"embeddable":true,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/speakers\/626638"}],"author":[{"embeddable":true,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wporg\/v1\/users\/fstaude"}],"wp:attachment":[{"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/media?parent=626787"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/session_track?post=626787"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/session_category?post=626787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}