{"id":626785,"date":"2014-05-15T19:22:47","date_gmt":"2014-05-15T17:22:47","guid":{"rendered":"https:\/\/2014.hamburg.wordcamp.org\/?post_type=wcb_session&#038;p=626785"},"modified":"2014-05-19T10:21:47","modified_gmt":"2014-05-19T08:21:47","slug":"wordpress-uebersetzen-core-plugins-und-themes","status":"publish","type":"wcb_session","link":"https:\/\/hamburg.wordcamp.org\/2014\/session\/wordpress-uebersetzen-core-plugins-und-themes\/","title":{"rendered":"WordPress \u00fcbersetzen: Core, Plugins und Themes"},"content":{"rendered":"<p>Speaker: Caspar H\u00fcbinger<\/p>\n<p>Diese Doppel-Session richtet sich an Plugin- und Theme-Entwickelnde, sowie WordPress-Anwender\/innen, die sich mit dem Thema Sprache und \u00dcbersetzung in und mit WordPress konfrontiert sehen.<br \/>\nBekannt sein d\u00fcrften <code>_e()<\/code> und <code>__()<\/code>. Wo die herkommen, gibt es ein ganzes Nest von der Sorte, und da pieksen wir mal kr\u00e4ftig rein. Au\u00dferdem werfen wir, f\u00fcr die tats\u00e4chlich \u00fcbersetzende Zunft, einen Blick auf \u00dcbersetzungstools und den Eingang zur Pforte des Gro\u00dfen Core.<\/p>\n<ul>\n<li>Grundlagen zu \u00dcbersetzung in WordPress<\/li>\n<li>F\u00fcr Entwickler\/innen:\n<ul>\n<li>Sprache in Plugins und Themes<\/li>\n<li>Strings, Text-Domains und Sprachdateien<\/li>\n<li>Kontext, Sicherheit<\/li>\n<\/ul>\n<\/li>\n<li>F\u00fcr \u00dcbersetzer\/innen:\n<ul>\n<li>Best Practices<\/li>\n<li>Plugins und Themes \u00fcbersetzen<\/li>\n<li>WordPress Core \u00fcbersetzen<\/li>\n<\/ul>\n<\/li>\n<li>Inhalte \u00fcbersetzen:\n<ul>\n<li>kurzer \u00dcberblick zu Szenarien und L\u00f6sungen<\/li>\n<li>Fragen und Antworten<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Nota bene: Den Themenkomplex \u201eMultilinguales WordPress\u201c (also mehrsprachige Inhalte) werden wir mit einem kurzen \u00dcberblick streifen; wenn du in dieses Thema tiefer einsteigen m\u00f6chtest, besuche am besten auch die Session \u201e<a title=\"Multilinguale WordPress Multisite\" href=\"https:\/\/2014.hamburg.wordcamp.org\/session\/multilinguale-wordpress-multisite\/\">Multilinguale WordPress-Multisite<\/a>\u201c von Friedhelm Oja!<\/p>\n<p>Themenbereich: Anwendung<br \/>\nZielgruppe: Fortgeschritten<br \/>\nFormat: Workshop<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Speaker: Caspar H\u00fcbinger Diese Doppel-Session richtet sich an Plugin- und Theme-Entwickelnde, sowie WordPress-Anwender\/innen, die sich mit dem Thema Sprache und \u00dcbersetzung in und mit WordPress konfrontiert sehen. Bekannt sein d\u00fcrften _e() und __(). Wo die herkommen, gibt es ein ganzes Nest von der Sorte, und da pieksen wir mal kr\u00e4ftig rein. Au\u00dferdem werfen wir, f\u00fcr [&hellip;]<\/p>\n","protected":false},"author":7658014,"featured_media":0,"template":"","meta":{"_wcpt_session_time":1402840800,"_wcpt_session_duration":3000,"_wcpt_session_type":"session","_wcpt_session_slides":"","_wcpt_session_video":"","_wcpt_speaker_id":[626636],"footnotes":""},"session_track":[298084],"session_category":[],"class_list":["post-626785","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-saal-3"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheVcj-2D3r","session_date_time":{"date":"15. Juni 2014","time":"16:00"},"session_speakers":[{"id":"626636","slug":"caspar-huebinger","name":"Caspar H\u00fcbinger","link":"https:\/\/hamburg.wordcamp.org\/2014\/speaker\/caspar-huebinger\/"}],"session_cats_rendered":null,"_links":{"self":[{"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/sessions\/626785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/types\/wcb_session"}],"version-history":[{"count":6,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/sessions\/626785\/revisions"}],"predecessor-version":[{"id":627082,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/sessions\/626785\/revisions\/627082"}],"speakers":[{"embeddable":true,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/speakers\/626636"}],"author":[{"embeddable":true,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wporg\/v1\/users\/anonymized_7658014"}],"wp:attachment":[{"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/media?parent=626785"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/session_track?post=626785"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/session_category?post=626785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}