{"id":626780,"date":"2014-05-15T18:53:05","date_gmt":"2014-05-15T16:53:05","guid":{"rendered":"https:\/\/2014.hamburg.wordcamp.org\/?post_type=wcb_session&#038;p=626780"},"modified":"2014-05-25T11:30:30","modified_gmt":"2014-05-25T09:30:30","slug":"in-objekten-denken-workshop-oop","status":"publish","type":"wcb_session","link":"https:\/\/hamburg.wordcamp.org\/2014\/session\/in-objekten-denken-workshop-oop\/","title":{"rendered":"In Objekten denken. Workshop OOP"},"content":{"rendered":"<p>Speaker:\u00a0Thomas Scholz<\/p>\n<p>Hast du schon einmal ein B\u00fcndel Funktionen in eine Klasse gesteckt, um weniger Pr\u00e4fixe verwenden zu m\u00fcssen oder eine Variable in mehreren Funktionen zu verwenden? So steigen viele Entwickler in die objekt-orientierte Programmierung ein. Aber wie geht es von hier aus weiter? Welche Funktionen geh\u00f6ren tats\u00e4chlich in ein gemeinsames Objekt, welche nicht? Wie kommunizieren Objekte miteinander?<\/p>\n<p>In diesem Workshop m\u00f6chte ich die Grundlagen objekt-orientierten Codes vorstellen, wie man prozeduralen Code erkennt und umschreibt (Refactoring) und welche Probleme man speziell in WordPress zu l\u00f6sen oder hinzunehmen hat.<\/p>\n<p><a href=\"http:\/\/toscho.de\/2014\/in-objekten-denken-konzept-fuer-das-wordcamp-hamburg\/\">Konzept f\u00fcr diese Session<\/a><\/p>\n<p>Themenbereich: Entwicklung<br \/>\nZielgruppe: Fortgeschritten<br \/>\nFormat: Workshop<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Speaker:\u00a0Thomas Scholz Hast du schon einmal ein B\u00fcndel Funktionen in eine Klasse gesteckt, um weniger Pr\u00e4fixe verwenden zu m\u00fcssen oder eine Variable in mehreren Funktionen zu verwenden? So steigen viele Entwickler in die objekt-orientierte Programmierung ein. Aber wie geht es von hier aus weiter? Welche Funktionen geh\u00f6ren tats\u00e4chlich in ein gemeinsames Objekt, welche nicht? Wie [&hellip;]<\/p>\n","protected":false},"author":2749838,"featured_media":0,"template":"","meta":{"_wcpt_session_time":1402825500,"_wcpt_session_duration":3000,"_wcpt_session_type":"session","_wcpt_session_slides":"","_wcpt_session_video":"","_wcpt_speaker_id":[626634],"footnotes":""},"session_track":[298084],"session_category":[],"class_list":["post-626780","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-saal-3"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheVcj-2D3m","session_date_time":{"date":"15. Juni 2014","time":"11:45"},"session_speakers":[{"id":"626634","slug":"thomas-scholz","name":"Thomas Scholz","link":"https:\/\/hamburg.wordcamp.org\/2014\/speaker\/thomas-scholz\/"}],"session_cats_rendered":null,"_links":{"self":[{"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/sessions\/626780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/types\/wcb_session"}],"version-history":[{"count":4,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/sessions\/626780\/revisions"}],"predecessor-version":[{"id":627308,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/sessions\/626780\/revisions\/627308"}],"speakers":[{"embeddable":true,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/speakers\/626634"}],"author":[{"embeddable":true,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wporg\/v1\/users\/thefuxia"}],"wp:attachment":[{"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/media?parent=626780"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/session_track?post=626780"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/session_category?post=626780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}