{"id":627287,"date":"2014-05-27T17:12:13","date_gmt":"2014-05-27T15:12:13","guid":{"rendered":"https:\/\/2014.hamburg.wordcamp.org\/?p=627287"},"modified":"2014-09-26T13:22:49","modified_gmt":"2014-09-26T11:22:49","slug":"danke-an-unsere-helfenden-haende","status":"publish","type":"post","link":"https:\/\/hamburg.wordcamp.org\/2014\/danke-an-unsere-helfenden-haende\/","title":{"rendered":"Danke Danke Danke an unsere helfenden H\u00e4nde!"},"content":{"rendered":"<p>Ein WordCamp organisiert sich nicht von alleine. Wenn es los geht und mehr als 300 BesucherInnen auf die Anmeldung st\u00fcrmen (ihr st\u00fcrmt doch, oder? \ud83d\ude09 ) dann braucht jedes Orga-Team <a title=\"Helfende H\u00e4nde\" href=\"https:\/\/2014.hamburg.wordcamp.org\/ueber\/helfende-haende\/\">HelferInnen<\/a>.<\/p>\n<p><!--more--><\/p>\n<p><strong>Wir sind begeistert von der WordPress-Community!<\/strong> Es haben sich <a title=\"Helfende H\u00e4nde\" href=\"https:\/\/2014.hamburg.wordcamp.org\/ueber\/helfende-haende\/\">zahlreiche Freiwillige<\/a> gemeldet die uns am Camp-Wochenende unterst\u00fctzen. Sie helfen uns beim Check-In, filmen die Sessions und helfen den SpeakerInnen beim Einrichten des Beamers und durch Anzeigen der noch verbleibenden Zeit.<\/p>\n<p>Ihr seid super! Auf deutsch gesagt AWESOME \ud83d\ude00<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein WordCamp organisiert sich nicht von alleine. Wenn es los geht und mehr als 300 BesucherInnen auf die Anmeldung st\u00fcrmen (ihr st\u00fcrmt doch, oder? \ud83d\ude09 ) dann braucht jedes Orga-Team HelferInnen.<\/p>\n","protected":false},"author":9891864,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[106],"tags":[306342,306041],"class_list":["post-627287","post","type-post","status-publish","format-standard","hentry","category-general","tag-freiwillige","tag-helferinnen"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheVcj-2Dbx","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/posts\/627287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/users\/9891864"}],"replies":[{"embeddable":true,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/comments?post=627287"}],"version-history":[{"count":6,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/posts\/627287\/revisions"}],"predecessor-version":[{"id":627338,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/posts\/627287\/revisions\/627338"}],"wp:attachment":[{"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/media?parent=627287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/categories?post=627287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hamburg.wordcamp.org\/2014\/wp-json\/wp\/v2\/tags?post=627287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}